{"id":2515,"date":"2026-02-18T13:51:01","date_gmt":"2026-02-18T13:51:01","guid":{"rendered":"https:\/\/fespa.es\/news\/?p=2515"},"modified":"2026-02-18T13:51:08","modified_gmt":"2026-02-18T13:51:08","slug":"entrevista-jesus-fespa-barcelona","status":"publish","type":"post","link":"https:\/\/fespa.es\/news\/index.php\/2026\/02\/18\/entrevista-jesus-fespa-barcelona\/","title":{"rendered":"El presidente de FESPA Espa\u00f1a analiza el retorno de FESPA a Barcelona en 2026"},"content":{"rendered":"\n<p><strong>FESPA entrevista al presidente de FESPA Espa\u00f1a, Jes\u00fas Dur\u00e1, para analizar el estado del sector y el papel de la feria FESPA como plataforma global. FESPA Global Print Expo vuelve a Barcelona del 19 al 22 de mayo de 2026.<\/strong><\/p>\n\n\n\n<p>Para Jes\u00fas Dur\u00e1, presidente de&nbsp;<a href=\"https:\/\/fespa.es\/\">FESPA Espa\u00f1a&nbsp;<\/a>y director general de&nbsp;<a href=\"https:\/\/www.vinylcolor.com\/\">Vinylcolor Digital,<\/a>&nbsp;el regreso del mayor evento global del sector supone un reconocimiento a la industria local y una oportunidad estrat\u00e9gica para las empresas espa\u00f1olas.<\/p>\n\n\n\n<p>\u201cEs un honor recibir a toda la comunidad gr\u00e1fica a nivel internacional\u201d, afirma Dur\u00e1. \u201cDespu\u00e9s de tantos a\u00f1os sin una FESPA Expo en Espa\u00f1a, volver a contar con FESPA Internacional en Barcelona es un motivo de satisfacci\u00f3n, pero tambi\u00e9n un reto\u201d.<\/p>\n\n\n\n<p><strong>UN ESCAPARATE GLOBAL QUE VUELVE A ESPA\u00d1A<\/strong><\/p>\n\n\n\n<p>La \u00faltima edici\u00f3n de FESPA celebrada en Espa\u00f1a tuvo lugar hace m\u00e1s de una d\u00e9cada. Desde entonces, el sector ha experimentado una profunda transformaci\u00f3n, marcada por la digitalizaci\u00f3n, la evoluci\u00f3n tecnol\u00f3gica y nuevos modelos de negocio. En este contexto, el retorno de la feria cobra un significado especial.<\/p>\n\n\n\n<p>\u201cFESPA es el mayor evento de la industria gr\u00e1fica a nivel global\u201d, subraya Dur\u00e1. \u201cQue vuelva a Espa\u00f1a despu\u00e9s de tantos a\u00f1os es un reconocimiento y un apoyo a la industria espa\u00f1ola\u201d.<\/p>\n\n\n\n<p>Adem\u00e1s, celebrar la feria en Barcelona reduce las barreras para muchas empresas locales. \u201cNo es lo mismo participar en una feria en tu propio pa\u00eds que desplazarte a un mercado de un tercer pa\u00eds\u201d, explica. \u201cEsto abre una oportunidad muy interesante para que m\u00e1s empresas espa\u00f1olas puedan mostrar sus productos y servicios, adem\u00e1s de incrementar de visitar la Expo como visitante\u201d.<\/p>\n\n\n\n<p><strong>UNA PLATAFORMA PARA LA INDUSTRIA LOCAL Y LA CONEXI\u00d3N CON AM\u00c9RICA LATINA<\/strong><\/p>\n\n\n\n<p>Dur\u00e1 destaca tambi\u00e9n el potencial de FESPA 2026 para reforzar los v\u00ednculos con otros mercados, especialmente con Latinoam\u00e9rica. \u201cEs una gran oportunidad para estrechar la relaci\u00f3n con Am\u00e9rica Latina\u201d, se\u00f1ala. \u201cTenemos facilidades culturales y de comunicaci\u00f3n que no siempre hemos sabido aprovechar del todo\u201d.<\/p>\n\n\n\n<p>M\u00e1s all\u00e1 del networking, FESPA act\u00faa como un punto de referencia para conocer el estado real del mercado. \u201cLa feria no es solo para hacer contactos\u201d, apunta. \u201cEs un espacio para entender hacia d\u00f3nde va el sector, qu\u00e9 se est\u00e1 desarrollando y cu\u00e1les son las perspectivas\u201d.<\/p>\n\n\n\n<p><strong>INNOVACI\u00d3N, MATERIALES Y TECNOLOG\u00cdA<\/strong><\/p>\n\n\n\n<p>Uno de los grandes ejes de transformaci\u00f3n del sector es la evoluci\u00f3n de los materiales, especialmente en relaci\u00f3n con la sostenibilidad. \u201cHoy es posible desarrollar estructuras completas, incluso stands, utilizando cart\u00f3n, algo impensable hace unos a\u00f1os\u201d, comenta Dur\u00e1.<\/p>\n\n\n\n<p>A ello se suma el avance constante de la tecnolog\u00eda de impresi\u00f3n. \u201cNuestro sector ha tenido que adaptarse muy r\u00e1pido a los cambios\u201d, afirma. \u201cProbablemente, en los \u00faltimos 20 a\u00f1os hemos vivido m\u00e1s transformaciones que desde Gutenberg hasta finales del siglo XX\u201d.<\/p>\n\n\n\n<p>La conectividad de los equipos, la gesti\u00f3n avanzada del color y la aplicaci\u00f3n de la inteligencia artificial est\u00e1n redefiniendo los procesos productivos. \u201cLa IA ya se puede aplicar tanto en la preimpresi\u00f3n como en la impresi\u00f3n, permitiendo detectar errores, mantener la consistencia del color o realizar mantenimiento predictivo\u201d, explica. \u201cEsto tiene un impacto directo en la productividad de las empresas\u201d.<\/p>\n\n\n\n<p><strong>SOSTENIBILIDAD: UNA VISI\u00d3N CR\u00cdTICA Y NECESARIA<\/strong><\/p>\n\n\n\n<p>Para Dur\u00e1, la sostenibilidad ya no es una opci\u00f3n, pero advierte de la necesidad de un an\u00e1lisis riguroso. \u201cHay que tener muy claro qu\u00e9 entendemos por sostenibilidad\u201d, afirma. \u201cNo todo lo que se presenta como sostenible lo es cuando analizas el proceso completo de reutilizaci\u00f3n del material\u201d.<\/p>\n\n\n\n<p>En su opini\u00f3n, el sector debe ser m\u00e1s transparente y cr\u00edtico, evitando tanto la demonizaci\u00f3n de ciertos materiales como la idealizaci\u00f3n de otros. \u201cSi apostamos por la sostenibilidad, debe ser con todas las consecuencias\u201d, se\u00f1ala, reconociendo que a\u00fan existe un diferencial de precios que el mercado debe asumir de forma gradual.<\/p>\n\n\n\n<p><strong>UNA CITA INELUDIBLE PARA EL SECTOR<\/strong><\/p>\n\n\n\n<p>Con presencia en 37 pa\u00edses, FESPA ofrece una plataforma \u00fanica para generar oportunidades a escala nacional e internacional. \u201cFESPA es el escaparate global que nos permite tomar el pulso real al mercado y tomar decisiones estrat\u00e9gicas\u201d, concluye Dur\u00e1. \u201cEs una cita ineludible para cualquiera que est\u00e9 preocupado por el futuro del sector y por la viabilidad de su empresa\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FESPA entrevista al presidente de FESPA Espa\u00f1a, Jes\u00fas Dur\u00e1, para analizar el estado del sector y el papel de la feria FESPA como plataforma global. FESPA Global Print Expo vuelve a Barcelona del 19 al 22 de mayo de 2026. Para Jes\u00fas Dur\u00e1, presidente de&nbsp;FESPA Espa\u00f1a&nbsp;y director general de&nbsp;Vinylcolor Digital,&nbsp;el regreso del mayor evento global&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,9,14],"tags":[],"class_list":["post-2515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas","category-fespa","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El presidente de FESPA Espa\u00f1a analiza el retorno de FESPA a Barcelona en 2026 - FESPA Espa\u00f1a Magazine<\/title>\n<meta name=\"description\" content=\"FESPA habla con el presidente de FESPA Espa\u00f1a para hablar sobre el impacto de la vuelta de la feria m\u00e1s importante del sector a Barcelona.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fespa.es\/news\/index.php\/test\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El presidente de FESPA Espa\u00f1a analiza el retorno de FESPA a Barcelona en 2026 - FESPA Espa\u00f1a Magazine\" \/>\n<meta property=\"og:description\" content=\"FESPA habla con el presidente de FESPA Espa\u00f1a para hablar sobre el impacto de la vuelta de la feria m\u00e1s importante del sector a Barcelona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fespa.es\/news\/index.php\/test\/\" \/>\n<meta property=\"og:site_name\" content=\"FESPA Espa\u00f1a Magazine\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-18T13:51:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-18T13:51:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2026\/02\/Fespa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/\",\"url\":\"https:\/\/fespa.es\/news\/index.php\/test\/\",\"name\":\"El presidente de FESPA Espa\u00f1a analiza el retorno de FESPA a Barcelona en 2026 - FESPA Espa\u00f1a Magazine\",\"isPartOf\":{\"@id\":\"https:\/\/fespa.es\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2026\/02\/Fespa.jpg\",\"datePublished\":\"2026-02-18T13:51:01+00:00\",\"dateModified\":\"2026-02-18T13:51:08+00:00\",\"author\":{\"@id\":\"https:\/\/fespa.es\/news\/#\/schema\/person\/0019098322836346476fc7dfdbd26d95\"},\"description\":\"FESPA habla con el presidente de FESPA Espa\u00f1a para hablar sobre el impacto de la vuelta de la feria m\u00e1s importante del sector a Barcelona.\",\"breadcrumb\":{\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fespa.es\/news\/index.php\/test\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage\",\"url\":\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2026\/02\/Fespa.jpg\",\"contentUrl\":\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2026\/02\/Fespa.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/fespa.es\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El presidente de FESPA Espa\u00f1a analiza el retorno de FESPA a Barcelona en 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fespa.es\/news\/#website\",\"url\":\"https:\/\/fespa.es\/news\/\",\"name\":\"FESPA Espa\u00f1a Magazine\",\"description\":\"El Peri\u00f3dico de la industria de la comunicaci\u00f3n visual\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fespa.es\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/fespa.es\/news\/#\/schema\/person\/0019098322836346476fc7dfdbd26d95\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fespa.es\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6a6c60542c39a2d052b8b1e8c5145e669bf888b9b229b3da0e43092daac8a32e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6a6c60542c39a2d052b8b1e8c5145e669bf888b9b229b3da0e43092daac8a32e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/fespa.es\/news\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El presidente de FESPA Espa\u00f1a analiza el retorno de FESPA a Barcelona en 2026 - FESPA Espa\u00f1a Magazine","description":"FESPA habla con el presidente de FESPA Espa\u00f1a para hablar sobre el impacto de la vuelta de la feria m\u00e1s importante del sector a Barcelona.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fespa.es\/news\/index.php\/test\/","og_locale":"es_ES","og_type":"article","og_title":"El presidente de FESPA Espa\u00f1a analiza el retorno de FESPA a Barcelona en 2026 - FESPA Espa\u00f1a Magazine","og_description":"FESPA habla con el presidente de FESPA Espa\u00f1a para hablar sobre el impacto de la vuelta de la feria m\u00e1s importante del sector a Barcelona.","og_url":"https:\/\/fespa.es\/news\/index.php\/test\/","og_site_name":"FESPA Espa\u00f1a Magazine","article_published_time":"2026-02-18T13:51:01+00:00","article_modified_time":"2026-02-18T13:51:08+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/fespa.es\/news\/wp-content\/uploads\/2026\/02\/Fespa.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fespa.es\/news\/index.php\/test\/","url":"https:\/\/fespa.es\/news\/index.php\/test\/","name":"El presidente de FESPA Espa\u00f1a analiza el retorno de FESPA a Barcelona en 2026 - FESPA Espa\u00f1a Magazine","isPartOf":{"@id":"https:\/\/fespa.es\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage"},"image":{"@id":"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage"},"thumbnailUrl":"https:\/\/fespa.es\/news\/wp-content\/uploads\/2026\/02\/Fespa.jpg","datePublished":"2026-02-18T13:51:01+00:00","dateModified":"2026-02-18T13:51:08+00:00","author":{"@id":"https:\/\/fespa.es\/news\/#\/schema\/person\/0019098322836346476fc7dfdbd26d95"},"description":"FESPA habla con el presidente de FESPA Espa\u00f1a para hablar sobre el impacto de la vuelta de la feria m\u00e1s importante del sector a Barcelona.","breadcrumb":{"@id":"https:\/\/fespa.es\/news\/index.php\/test\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fespa.es\/news\/index.php\/test\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage","url":"https:\/\/fespa.es\/news\/wp-content\/uploads\/2026\/02\/Fespa.jpg","contentUrl":"https:\/\/fespa.es\/news\/wp-content\/uploads\/2026\/02\/Fespa.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/fespa.es\/news\/index.php\/test\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fespa.es\/news\/"},{"@type":"ListItem","position":2,"name":"El presidente de FESPA Espa\u00f1a analiza el retorno de FESPA a Barcelona en 2026"}]},{"@type":"WebSite","@id":"https:\/\/fespa.es\/news\/#website","url":"https:\/\/fespa.es\/news\/","name":"FESPA Espa\u00f1a Magazine","description":"El Peri\u00f3dico de la industria de la comunicaci\u00f3n visual","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fespa.es\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/fespa.es\/news\/#\/schema\/person\/0019098322836346476fc7dfdbd26d95","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fespa.es\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6a6c60542c39a2d052b8b1e8c5145e669bf888b9b229b3da0e43092daac8a32e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a6c60542c39a2d052b8b1e8c5145e669bf888b9b229b3da0e43092daac8a32e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/fespa.es\/news\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/posts\/2515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/comments?post=2515"}],"version-history":[{"count":1,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/posts\/2515\/revisions"}],"predecessor-version":[{"id":2517,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/posts\/2515\/revisions\/2517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/media\/2516"}],"wp:attachment":[{"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/media?parent=2515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/categories?post=2515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/tags?post=2515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}