{"id":2127,"date":"2024-02-06T15:47:13","date_gmt":"2024-02-06T15:47:13","guid":{"rendered":"https:\/\/fespa.es\/news\/?p=2127"},"modified":"2024-05-09T15:20:23","modified_gmt":"2024-05-09T15:20:23","slug":"redbond-composites-recibe-la-visita-del-alcalde-de-alicante-luis-barcala","status":"publish","type":"post","link":"https:\/\/fespa.es\/news\/index.php\/2024\/02\/06\/redbond-composites-recibe-la-visita-del-alcalde-de-alicante-luis-barcala\/","title":{"rendered":"RedBOND Composites recibe la visita del alcalde de Alicante, Luis Barcala"},"content":{"rendered":"\n<p>RedBOND Composites, la empresa del Grupo Alib\u00e9rico especializada en la fabricaci\u00f3n de paneles composite de aluminio para impresi\u00f3n digital y comunicaci\u00f3n visual, ha recibido en su f\u00e1brica del Pol\u00edgono Industrial de Aguamarga la visita del alcalde de Alicante, Luis Barcala, que ha estado acompa\u00f1ado por la coordinadora general de Gesti\u00f3n Municipal, Asunci\u00f3n Mart\u00ednez, y por la concejala de Empleo y Fomento, M\u00aa Carmen de Espa\u00f1a.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-Clemente-Glez-Soler-pte-Aliberico-con-Luis-Barcala-alcalde-Alicante-1024x684.jpg\" alt=\"\" class=\"wp-image-2130\" srcset=\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-Clemente-Glez-Soler-pte-Aliberico-con-Luis-Barcala-alcalde-Alicante-1024x684.jpg 1024w, https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-Clemente-Glez-Soler-pte-Aliberico-con-Luis-Barcala-alcalde-Alicante-300x200.jpg 300w, https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-Clemente-Glez-Soler-pte-Aliberico-con-Luis-Barcala-alcalde-Alicante-768x513.jpg 768w, https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-Clemente-Glez-Soler-pte-Aliberico-con-Luis-Barcala-alcalde-Alicante-1536x1027.jpg 1536w, https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-Clemente-Glez-Soler-pte-Aliberico-con-Luis-Barcala-alcalde-Alicante-480x321.jpg 480w, https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-Clemente-Glez-Soler-pte-Aliberico-con-Luis-Barcala-alcalde-Alicante-748x500.jpg 748w, https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-Clemente-Glez-Soler-pte-Aliberico-con-Luis-Barcala-alcalde-Alicante.jpg 1616w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption><sub>Luis Barcala en su visita a las instalaciones de RedBOND Composites<\/sub><\/figcaption><\/figure>\n\n\n\n<p>En su visita a la planta industrial, las autoridades municipales han sido recibidas por el presidente del Grupo Alib\u00e9rico, Clemente Gonz\u00e1lez Soler, y por la gerente de RedBOND, Mar\u00eda Gonz\u00e1lez Armero.&nbsp;<\/p>\n\n\n\n<p>La visita se ha iniciado con una&nbsp;presentaci\u00f3n de la compa\u00f1\u00eda en la que&nbsp;se ha puesto de relieve su actividad innovadora y su compromiso medioambiental, social y de gobierno corporativo (ESG) a trav\u00e9s de la transformaci\u00f3n del aluminio.&nbsp;<\/p>\n\n\n\n<p>Uno de los aspectos destacados en la visita ha sido el esfuerzo que la compa\u00f1\u00eda viene realizando en los \u00faltimos a\u00f1os en materia de sostenibilidad. Desde hace solo un mes, RedBOND se ha convertido en el primer fabricante europeo dentro de su sector en lograr la certificaci\u00f3n Neutro en Carbono, lo que supone en la pr\u00e1ctica que la compa\u00f1\u00eda lanza a la atm\u00f3sfera cero emisiones netas de CO2.&nbsp;<\/p>\n\n\n\n<p>Asimismo, se ha subrayado la importante contribuci\u00f3n de la industria a la generaci\u00f3n de un empleo estable y de calidad, una realidad de la que es ejemplo la compa\u00f1\u00eda RedBOND, cuya plantilla, al 100%, est\u00e1 compuesta por empleados con contratos indefinidos.&nbsp;<\/p>\n\n\n\n<p>Durante el recorrido, las autoridades tuvieron la oportunidad de conocer las dos l\u00edneas de producci\u00f3n en continuo de paneles dise\u00f1adas con tecnolog\u00eda propia y el nuevo proyecto de ampliaci\u00f3n que RedBOND ha acometido para dotarse de un nuevo almac\u00e9n y poder incrementar tanto su actividad como su capacidad log\u00edstica.<\/p>\n\n\n\n<p>Luis Mascar\u00f3 Capdevila, presidente de la Junta Directiva de EGM Aguamarga y de la Federaci\u00f3n de Empresarios del Metal de Alicante (FEMPA), y Vicente J. Segu\u00ed Pic\u00f3, vicepresidente de la Federaci\u00f3n de Parques Empresariales de la Comunidad Valenciana (FEPEVAL), tambi\u00e9n asistieron a la visita de RedBOND, coincidiendo con la ratificaci\u00f3n del acto de constituci\u00f3n de la comisi\u00f3n promotora de la Entidad de Gesti\u00f3n y Modernizaci\u00f3n&nbsp;(EGM) del&nbsp;\u00c1rea&nbsp;Industrial&nbsp;Aguamarga. Esta entidad se propone aumentar el atractivo de esta zona industrial de cara a potenciar la inversi\u00f3n empresarial, y para ello prev\u00e9 mejorar su funcionalidad y sostenibilidad con el fin de incrementar su impacto econ\u00f3mico y social.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RedBOND Composites, la empresa del Grupo Alib\u00e9rico especializada en la fabricaci\u00f3n de paneles composite de aluminio para impresi\u00f3n digital y comunicaci\u00f3n visual, ha recibido en su f\u00e1brica del Pol\u00edgono Industrial de Aguamarga la visita del alcalde de Alicante, Luis Barcala, que ha estado acompa\u00f1ado por la coordinadora general de Gesti\u00f3n Municipal, Asunci\u00f3n Mart\u00ednez, y por&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2128,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,14],"tags":[],"class_list":["post-2127","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asociados","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RedBOND Composites recibe la visita del alcalde de Alicante, Luis Barcala - FESPA Espa\u00f1a Magazine<\/title>\n<meta name=\"description\" content=\"RedBOND Composites, ha recibido en su f\u00e1brica del Pol\u00edgono Industrial de Aguamarga la visita del alcalde de Alicante, Luis Barcala.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fespa.es\/news\/index.php\/test\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RedBOND Composites recibe la visita del alcalde de Alicante, Luis Barcala - FESPA Espa\u00f1a Magazine\" \/>\n<meta property=\"og:description\" content=\"RedBOND Composites, ha recibido en su f\u00e1brica del Pol\u00edgono Industrial de Aguamarga la visita del alcalde de Alicante, Luis Barcala.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fespa.es\/news\/index.php\/test\/\" \/>\n<meta property=\"og:site_name\" content=\"FESPA Espa\u00f1a Magazine\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-06T15:47:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-09T15:20:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-De-izda-a-dcha-Asuncion-Martinez-Maria-Gonzalez-Armero-Luis-Barcala-Clemente-Gonzalez-Soler-y-Ma-Carmen-de-Espana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1616\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/\",\"url\":\"https:\/\/fespa.es\/news\/index.php\/test\/\",\"name\":\"RedBOND Composites recibe la visita del alcalde de Alicante, Luis Barcala - FESPA Espa\u00f1a Magazine\",\"isPartOf\":{\"@id\":\"https:\/\/fespa.es\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-De-izda-a-dcha-Asuncion-Martinez-Maria-Gonzalez-Armero-Luis-Barcala-Clemente-Gonzalez-Soler-y-Ma-Carmen-de-Espana.jpg\",\"datePublished\":\"2024-02-06T15:47:13+00:00\",\"dateModified\":\"2024-05-09T15:20:23+00:00\",\"author\":{\"@id\":\"https:\/\/fespa.es\/news\/#\/schema\/person\/0019098322836346476fc7dfdbd26d95\"},\"description\":\"RedBOND Composites, ha recibido en su f\u00e1brica del Pol\u00edgono Industrial de Aguamarga la visita del alcalde de Alicante, Luis Barcala.\",\"breadcrumb\":{\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fespa.es\/news\/index.php\/test\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage\",\"url\":\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-De-izda-a-dcha-Asuncion-Martinez-Maria-Gonzalez-Armero-Luis-Barcala-Clemente-Gonzalez-Soler-y-Ma-Carmen-de-Espana.jpg\",\"contentUrl\":\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-De-izda-a-dcha-Asuncion-Martinez-Maria-Gonzalez-Armero-Luis-Barcala-Clemente-Gonzalez-Soler-y-Ma-Carmen-de-Espana.jpg\",\"width\":1616,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/fespa.es\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RedBOND Composites recibe la visita del alcalde de Alicante, Luis Barcala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fespa.es\/news\/#website\",\"url\":\"https:\/\/fespa.es\/news\/\",\"name\":\"FESPA Espa\u00f1a Magazine\",\"description\":\"El Peri\u00f3dico de la industria de la comunicaci\u00f3n visual\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fespa.es\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/fespa.es\/news\/#\/schema\/person\/0019098322836346476fc7dfdbd26d95\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fespa.es\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6a6c60542c39a2d052b8b1e8c5145e669bf888b9b229b3da0e43092daac8a32e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6a6c60542c39a2d052b8b1e8c5145e669bf888b9b229b3da0e43092daac8a32e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/fespa.es\/news\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RedBOND Composites recibe la visita del alcalde de Alicante, Luis Barcala - FESPA Espa\u00f1a Magazine","description":"RedBOND Composites, ha recibido en su f\u00e1brica del Pol\u00edgono Industrial de Aguamarga la visita del alcalde de Alicante, Luis Barcala.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fespa.es\/news\/index.php\/test\/","og_locale":"es_ES","og_type":"article","og_title":"RedBOND Composites recibe la visita del alcalde de Alicante, Luis Barcala - FESPA Espa\u00f1a Magazine","og_description":"RedBOND Composites, ha recibido en su f\u00e1brica del Pol\u00edgono Industrial de Aguamarga la visita del alcalde de Alicante, Luis Barcala.","og_url":"https:\/\/fespa.es\/news\/index.php\/test\/","og_site_name":"FESPA Espa\u00f1a Magazine","article_published_time":"2024-02-06T15:47:13+00:00","article_modified_time":"2024-05-09T15:20:23+00:00","og_image":[{"width":1616,"height":1080,"url":"https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-De-izda-a-dcha-Asuncion-Martinez-Maria-Gonzalez-Armero-Luis-Barcala-Clemente-Gonzalez-Soler-y-Ma-Carmen-de-Espana.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fespa.es\/news\/index.php\/test\/","url":"https:\/\/fespa.es\/news\/index.php\/test\/","name":"RedBOND Composites recibe la visita del alcalde de Alicante, Luis Barcala - FESPA Espa\u00f1a Magazine","isPartOf":{"@id":"https:\/\/fespa.es\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage"},"image":{"@id":"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage"},"thumbnailUrl":"https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-De-izda-a-dcha-Asuncion-Martinez-Maria-Gonzalez-Armero-Luis-Barcala-Clemente-Gonzalez-Soler-y-Ma-Carmen-de-Espana.jpg","datePublished":"2024-02-06T15:47:13+00:00","dateModified":"2024-05-09T15:20:23+00:00","author":{"@id":"https:\/\/fespa.es\/news\/#\/schema\/person\/0019098322836346476fc7dfdbd26d95"},"description":"RedBOND Composites, ha recibido en su f\u00e1brica del Pol\u00edgono Industrial de Aguamarga la visita del alcalde de Alicante, Luis Barcala.","breadcrumb":{"@id":"https:\/\/fespa.es\/news\/index.php\/test\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fespa.es\/news\/index.php\/test\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage","url":"https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-De-izda-a-dcha-Asuncion-Martinez-Maria-Gonzalez-Armero-Luis-Barcala-Clemente-Gonzalez-Soler-y-Ma-Carmen-de-Espana.jpg","contentUrl":"https:\/\/fespa.es\/news\/wp-content\/uploads\/2024\/02\/20240202-De-izda-a-dcha-Asuncion-Martinez-Maria-Gonzalez-Armero-Luis-Barcala-Clemente-Gonzalez-Soler-y-Ma-Carmen-de-Espana.jpg","width":1616,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/fespa.es\/news\/index.php\/test\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fespa.es\/news\/"},{"@type":"ListItem","position":2,"name":"RedBOND Composites recibe la visita del alcalde de Alicante, Luis Barcala"}]},{"@type":"WebSite","@id":"https:\/\/fespa.es\/news\/#website","url":"https:\/\/fespa.es\/news\/","name":"FESPA Espa\u00f1a Magazine","description":"El Peri\u00f3dico de la industria de la comunicaci\u00f3n visual","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fespa.es\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/fespa.es\/news\/#\/schema\/person\/0019098322836346476fc7dfdbd26d95","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fespa.es\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6a6c60542c39a2d052b8b1e8c5145e669bf888b9b229b3da0e43092daac8a32e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a6c60542c39a2d052b8b1e8c5145e669bf888b9b229b3da0e43092daac8a32e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/fespa.es\/news\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/posts\/2127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/comments?post=2127"}],"version-history":[{"count":3,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/posts\/2127\/revisions"}],"predecessor-version":[{"id":2132,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/posts\/2127\/revisions\/2132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/media\/2128"}],"wp:attachment":[{"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/media?parent=2127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/categories?post=2127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/tags?post=2127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}