{"id":1904,"date":"2023-04-17T16:52:08","date_gmt":"2023-04-17T16:52:08","guid":{"rendered":"https:\/\/fespa.es\/news\/?p=1904"},"modified":"2023-04-17T16:52:18","modified_gmt":"2023-04-17T16:52:18","slug":"los-ganadores-de-los-premios-fespa-2023-se-anunciaran-en-fespa-global-print-expo-2023","status":"publish","type":"post","link":"https:\/\/fespa.es\/news\/index.php\/2023\/04\/17\/los-ganadores-de-los-premios-fespa-2023-se-anunciaran-en-fespa-global-print-expo-2023\/","title":{"rendered":"Los ganadores de los Premios FESPA 2023 se anunciar\u00e1n en FESPA Global Print Expo 2023"},"content":{"rendered":"\n<p><strong>Los Premios FESPA 2023 ahora han sido juzgados por nuestro panel de expertos de la industria y se anunciaron las entradas preseleccionadas. Los premios FESPA celebran la excelencia en la impresi\u00f3n y los logros de los impresores y rotulistas de todo el mundo, adem\u00e1s de reconocer su talento, habilidad, creatividad e innovaci\u00f3n.&nbsp;<\/strong><\/p>\n\n\n\n<p>La \u00faltima edici\u00f3n de los Premios FESPA tuvo lugar en 2020 antes del COVID. Este a\u00f1o, se presentaron 210 entradas de m\u00e1s de 30 pa\u00edses en 18 categor\u00edas de especialidad, lo que representa un aumento del 20 % de las entradas en comparaci\u00f3n con las entradas de 2020.<strong><\/strong><\/p>\n\n\n\n<p><strong>Categor\u00edas de premios<\/strong><\/p>\n\n\n\n<p>Hubo 22 categor\u00edas de premios en total que variaban desde papel y cart\u00f3n, carteles, envoltorios, efectos especiales creativos, impresi\u00f3n funcional hasta otras categor\u00edas como el Premio Printeriors y el Premio Estrella Joven. 4 de estas categor\u00edas de premios eran categor\u00edas de premios adicionales que inclu\u00edan el premio People&#8217;s Choice, el premio Best in Show, el premio Judges for Innovation y el premio Judges for Sustainability. Para obtener la lista completa de los&nbsp;<a href=\"https:\/\/www.fespaawards.com\/\">premios FESPA<\/a>&nbsp;, consulte a continuaci\u00f3n.<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\"><li>Display y POP en papel y cart\u00f3n<\/li><li>Embalaje en papel y cart\u00f3n<\/li><li>Display y POP en Pl\u00e1stico<\/li><li>Embalaje en Pl\u00e1sticos<\/li><li>carteles<\/li><li>Serigraf\u00edas y Gicl\u00e9e y reproducciones de Bellas Artes, libros, folletos.<\/li><li>Calcoman\u00edas y etiquetas impresas &#8211; Calcoman\u00edas, etiquetas impresas, marcado de flotas, vinilos para ventanas, etc.<\/li><li>Envase<\/li><li>Efectos Especiales Creativos &#8211; Cart\u00f3n y pl\u00e1sticos<\/li><li>Efecto especial en camisetas, prendas y otros textiles<\/li><li>Prendas estampadas: serigraf\u00eda, impresi\u00f3n directa a la prenda, transferencias, impresi\u00f3n por sublimaci\u00f3n de tinta en prendas prefabricadas.<\/li><li>Textiles impresos rollo a rollo<\/li><li>Productos de vidrio, cer\u00e1mica, metal y madera<\/li><li>Impresi\u00f3n directa en productos tridimensionales<\/li><li>Se\u00f1alizaci\u00f3n no impresa<\/li><li>Impresi\u00f3n funcional<\/li><li>Premio Printeriors<\/li><li>Premio Young Star: este premio est\u00e1 marcado en todas las categor\u00edas y tiene dos subcategor\u00edas; aprendiz profesional en impresi\u00f3n digital o serigr\u00e1fica y estudiante de dise\u00f1o para impresi\u00f3n digital o serigr\u00e1fica.<\/li><\/ol>\n\n\n\n<p>De 210 solicitudes, 170 entradas fueron preseleccionadas. Para cada premio, los participantes elegidos recibir\u00e1n premios de oro, plata y bronce en funci\u00f3n del cumplimiento de los altos est\u00e1ndares esperados por los jueces. Estos premios se anunciar\u00e1n en\u00a0<a href=\"https:\/\/www.fespaglobalprintexpo.com\/\">FESPA Global Print Expo 2023<\/a>el 24\u00a0<sup>de<\/sup>\u00a0mayo.<\/p>\n\n\n\n<p><strong><u>Jueces del premio FESPA<\/u><\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2023\/04\/Imagen-2.png\" alt=\"\" class=\"wp-image-1905\" width=\"-204\" height=\"-83\" srcset=\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2023\/04\/Imagen-2.png 941w, https:\/\/fespa.es\/news\/wp-content\/uploads\/2023\/04\/Imagen-2-300x124.png 300w, https:\/\/fespa.es\/news\/wp-content\/uploads\/2023\/04\/Imagen-2-768x317.png 768w, https:\/\/fespa.es\/news\/wp-content\/uploads\/2023\/04\/Imagen-2-480x198.png 480w\" sizes=\"(max-width: 941px) 100vw, 941px\" \/><\/figure><\/div>\n\n\n\n<p><br>Todas las participaciones en los premios fueron otorgadas por nuestro panel de expertos de la industria. Los jueces del Premio FESPA mantienen su compromiso de mantener los m\u00e1s altos est\u00e1ndares al evaluar las entradas. El panel de jueces combinado tiene 120 a\u00f1os de experiencia. Este a\u00f1o, los jueces recibieron un alto calibre de entradas de premios que mostraron una innovaci\u00f3n y un acabado excepcionales. Este a\u00f1o hubo un aumento evidente en las presentaciones con un mayor grado de pensamiento sostenible que refleja las tendencias del mercado.<br><br>Graeme Richardson-Locke es director de asociaciones y director t\u00e9cnico de FESPA. Graeme tiene casi 40 a\u00f1os de experiencia en las industrias de impresi\u00f3n digital de gran formato y serigraf\u00eda, con conocimientos adquiridos a trav\u00e9s de la gesti\u00f3n pr\u00e1ctica de dise\u00f1o, producci\u00f3n, ventas y operaciones. Graeme tambi\u00e9n es miembro de ASDPT, la Academia de tecnolog\u00edas de impresi\u00f3n digital y serigr\u00e1fica con sede en EE. UU.<br><br>Graeme coment\u00f3: \u201c<em>Juzgar la competencia de los Premios FESPA para 2023 ha sido inspirador y desafiante en igual medida, pero es algo que siempre espero con ansias. El proceso y los criterios est\u00e1n bien establecidos y las categor\u00edas est\u00e1n claramente definidas, pero la gama de procesos de impresi\u00f3n y t\u00e9cnicas de aplicaci\u00f3n es enorme, por lo que se necesita mucho compromiso para evaluar m\u00e1s de 200 proyectos separados. Contar con el apoyo de nuestros jueces con una experiencia combinada de m\u00e1s de 120 a\u00f1os proporciona la informaci\u00f3n necesaria para realizar el trabajo. Este a\u00f1o ve una gran cantidad de trabajo inteligente, creativo y expansivo de nuestra comunidad internacional de impresi\u00f3n, y puedo prometer una lista corta de trabajo muy cre\u00edble. Los anuncios finales los har\u00e9 yo junto con otros jueces, Jacek Stencel y Debbie McKeegan durante la FESPA Global Print Expo en mayo, momento en el que disfrutaremos honrando a los ganadores cuando reciban sus premios. Por supuesto, tengo muchas ganas de ver la exhibici\u00f3n completa de la colecci\u00f3n preseleccionada en el piso de exhibici\u00f3n<\/em>\u201d.<br><br>Debbie McKeegan es la directora general de Texintel y tiene m\u00e1s de 25 a\u00f1os de experiencia en la industria textil. Es una dise\u00f1adora textil galardonada, adem\u00e1s de ser embajadora textil de FESPA. Debbie coment\u00f3: \u201c<em>Los premios FESPA re\u00fanen a la comunidad de impresi\u00f3n en muchos mercados, m\u00faltiples aplicaciones y tecnolog\u00edas: digital y de pantalla. Es un honor poder presenciar el desarrollo de la industria y ver de primera mano c\u00f3mo el talento y la tecnolog\u00eda est\u00e1n ampliando la gama de la impresi\u00f3n. Las entradas de este a\u00f1o incluyeron muchas innovaciones y proyectos de impresi\u00f3n (grandes y peque\u00f1os). Cada uno de los cuales es fascinante de estudiar y siempre es un desaf\u00edo elegir a los ganadores. Hubo m\u00faltiples proyectos destacados este a\u00f1o, lo que hizo que la tarea fuera a\u00fan m\u00e1s dif\u00edcil para nuestros jueces. En todos los mercados, la comunidad de impresi\u00f3n contin\u00faa ampliando los l\u00edmites del desarrollo de productos y la innovaci\u00f3n t\u00e9cnica para ofrecer excelencia y nuevas oportunidades comerciales<\/em>\u201d.<br><br>Jacek Stencel es el propietario y fundador de PASJA, una empresa de serigraf\u00eda e impresi\u00f3n digital en Polonia, adem\u00e1s de ser el presidente de FESPA de la Asociaci\u00f3n Polaca de FESPA, PSSiDC. Jacek tiene m\u00e1s de 35 a\u00f1os de experiencia y tambi\u00e9n es miembro de la Academia de EE. UU. ASDPT. Coment\u00f3: \u201c<em>Es un gran honor y un privilegio que una vez m\u00e1s me hayan invitado a ser juez en la edici\u00f3n de este a\u00f1o de los Premios FESPA. La oportunidad de trabajar con un equipo de profesionales que juzga m\u00e1s de 200 presentaciones es incre\u00edblemente emocionante para m\u00ed, adem\u00e1s de un desaf\u00edo para elegir las mejores entradas. Hubo muchos ejemplos que mostraron el poder de la creatividad, la innovaci\u00f3n y la sostenibilidad<\/em>\u201d.<br><br><strong>La ceremonia de los Premios FESPA 2023 tendr\u00e1 lugar el mi\u00e9rcoles 24\u00a0<sup>de<\/sup>\u00a0mayo en<\/strong>\u00a0<a href=\"https:\/\/www.fespaglobalprintexpo.com\/\"><strong>FESPA Global Print Expo 2023<\/strong><\/a>\u00a0<strong>en Messe Munich en Alemania. Los participantes preseleccionados ser\u00e1n invitados a esta glamorosa ceremonia donde se anunciar\u00e1n los ganadores de cada categor\u00eda de premios y se les entregar\u00e1n sus premios. Reg\u00edstrese aqu\u00ed para visitar FESPA Global Print Expo 2023 y ver la ceremonia de los premios FESPA. Usa el c\u00f3digo\u00a0<u>FESJ304<\/u>\u00a0para recibir un descuento de 30 euros y paga 50 euros por tu entrada.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Premios FESPA 2023 ahora han sido juzgados por nuestro panel de expertos de la industria y se anunciaron las entradas preseleccionadas. Los premios FESPA celebran la excelencia en la impresi\u00f3n y los logros de los impresores y rotulistas de todo el mundo, adem\u00e1s de reconocer su talento, habilidad, creatividad e innovaci\u00f3n.&nbsp; La \u00faltima edici\u00f3n&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1906,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,9,14],"tags":[],"class_list":["post-1904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-sector","category-fespa","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los ganadores de los Premios FESPA 2023 se anunciar\u00e1n en FESPA Global Print Expo 2023 - FESPA Espa\u00f1a Magazine<\/title>\n<meta name=\"description\" content=\"Los Premios FESPA 2023 ahora han sido juzgados por nuestro panel de expertos de la industria y se anunciaron las entradas preseleccionadas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fespa.es\/news\/index.php\/test\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los ganadores de los Premios FESPA 2023 se anunciar\u00e1n en FESPA Global Print Expo 2023 - FESPA Espa\u00f1a Magazine\" \/>\n<meta property=\"og:description\" content=\"Los Premios FESPA 2023 ahora han sido juzgados por nuestro panel de expertos de la industria y se anunciaron las entradas preseleccionadas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fespa.es\/news\/index.php\/test\/\" \/>\n<meta property=\"og:site_name\" content=\"FESPA Espa\u00f1a Magazine\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-17T16:52:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-17T16:52:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2023\/04\/Imagen-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"762\" \/>\n\t<meta property=\"og:image:height\" content=\"508\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/\",\"url\":\"https:\/\/fespa.es\/news\/index.php\/test\/\",\"name\":\"Los ganadores de los Premios FESPA 2023 se anunciar\u00e1n en FESPA Global Print Expo 2023 - FESPA Espa\u00f1a Magazine\",\"isPartOf\":{\"@id\":\"https:\/\/fespa.es\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2023\/04\/Imagen-1.png\",\"datePublished\":\"2023-04-17T16:52:08+00:00\",\"dateModified\":\"2023-04-17T16:52:18+00:00\",\"author\":{\"@id\":\"https:\/\/fespa.es\/news\/#\/schema\/person\/0019098322836346476fc7dfdbd26d95\"},\"description\":\"Los Premios FESPA 2023 ahora han sido juzgados por nuestro panel de expertos de la industria y se anunciaron las entradas preseleccionadas\",\"breadcrumb\":{\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fespa.es\/news\/index.php\/test\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage\",\"url\":\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2023\/04\/Imagen-1.png\",\"contentUrl\":\"https:\/\/fespa.es\/news\/wp-content\/uploads\/2023\/04\/Imagen-1.png\",\"width\":762,\"height\":508},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fespa.es\/news\/index.php\/test\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/fespa.es\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los ganadores de los Premios FESPA 2023 se anunciar\u00e1n en FESPA Global Print Expo 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fespa.es\/news\/#website\",\"url\":\"https:\/\/fespa.es\/news\/\",\"name\":\"FESPA Espa\u00f1a Magazine\",\"description\":\"El Peri\u00f3dico de la industria de la comunicaci\u00f3n visual\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fespa.es\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/fespa.es\/news\/#\/schema\/person\/0019098322836346476fc7dfdbd26d95\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fespa.es\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6a6c60542c39a2d052b8b1e8c5145e669bf888b9b229b3da0e43092daac8a32e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6a6c60542c39a2d052b8b1e8c5145e669bf888b9b229b3da0e43092daac8a32e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/fespa.es\/news\/index.php\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los ganadores de los Premios FESPA 2023 se anunciar\u00e1n en FESPA Global Print Expo 2023 - FESPA Espa\u00f1a Magazine","description":"Los Premios FESPA 2023 ahora han sido juzgados por nuestro panel de expertos de la industria y se anunciaron las entradas preseleccionadas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fespa.es\/news\/index.php\/test\/","og_locale":"es_ES","og_type":"article","og_title":"Los ganadores de los Premios FESPA 2023 se anunciar\u00e1n en FESPA Global Print Expo 2023 - FESPA Espa\u00f1a Magazine","og_description":"Los Premios FESPA 2023 ahora han sido juzgados por nuestro panel de expertos de la industria y se anunciaron las entradas preseleccionadas","og_url":"https:\/\/fespa.es\/news\/index.php\/test\/","og_site_name":"FESPA Espa\u00f1a Magazine","article_published_time":"2023-04-17T16:52:08+00:00","article_modified_time":"2023-04-17T16:52:18+00:00","og_image":[{"width":762,"height":508,"url":"https:\/\/fespa.es\/news\/wp-content\/uploads\/2023\/04\/Imagen-1.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fespa.es\/news\/index.php\/test\/","url":"https:\/\/fespa.es\/news\/index.php\/test\/","name":"Los ganadores de los Premios FESPA 2023 se anunciar\u00e1n en FESPA Global Print Expo 2023 - FESPA Espa\u00f1a Magazine","isPartOf":{"@id":"https:\/\/fespa.es\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage"},"image":{"@id":"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage"},"thumbnailUrl":"https:\/\/fespa.es\/news\/wp-content\/uploads\/2023\/04\/Imagen-1.png","datePublished":"2023-04-17T16:52:08+00:00","dateModified":"2023-04-17T16:52:18+00:00","author":{"@id":"https:\/\/fespa.es\/news\/#\/schema\/person\/0019098322836346476fc7dfdbd26d95"},"description":"Los Premios FESPA 2023 ahora han sido juzgados por nuestro panel de expertos de la industria y se anunciaron las entradas preseleccionadas","breadcrumb":{"@id":"https:\/\/fespa.es\/news\/index.php\/test\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fespa.es\/news\/index.php\/test\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fespa.es\/news\/index.php\/test\/#primaryimage","url":"https:\/\/fespa.es\/news\/wp-content\/uploads\/2023\/04\/Imagen-1.png","contentUrl":"https:\/\/fespa.es\/news\/wp-content\/uploads\/2023\/04\/Imagen-1.png","width":762,"height":508},{"@type":"BreadcrumbList","@id":"https:\/\/fespa.es\/news\/index.php\/test\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fespa.es\/news\/"},{"@type":"ListItem","position":2,"name":"Los ganadores de los Premios FESPA 2023 se anunciar\u00e1n en FESPA Global Print Expo 2023"}]},{"@type":"WebSite","@id":"https:\/\/fespa.es\/news\/#website","url":"https:\/\/fespa.es\/news\/","name":"FESPA Espa\u00f1a Magazine","description":"El Peri\u00f3dico de la industria de la comunicaci\u00f3n visual","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fespa.es\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/fespa.es\/news\/#\/schema\/person\/0019098322836346476fc7dfdbd26d95","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fespa.es\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6a6c60542c39a2d052b8b1e8c5145e669bf888b9b229b3da0e43092daac8a32e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a6c60542c39a2d052b8b1e8c5145e669bf888b9b229b3da0e43092daac8a32e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/fespa.es\/news\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/posts\/1904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/comments?post=1904"}],"version-history":[{"count":1,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/posts\/1904\/revisions"}],"predecessor-version":[{"id":1907,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/posts\/1904\/revisions\/1907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/media\/1906"}],"wp:attachment":[{"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/media?parent=1904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/categories?post=1904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fespa.es\/news\/index.php\/wp-json\/wp\/v2\/tags?post=1904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}